{"id":4812,"date":"2019-12-17T13:10:01","date_gmt":"2019-12-17T18:10:01","guid":{"rendered":"https:\/\/dormalab.com\/your-dentist-could-detect-your-sleep-apnea\/"},"modified":"2021-05-12T11:34:24","modified_gmt":"2021-05-12T15:34:24","slug":"votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil","status":"publish","type":"post","link":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/","title":{"rendered":"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil"},"content":{"rendered":"<p>[vc_row][vc_column width=\u00a0\u00bb3\/12&Prime; el_class=\u00a0\u00bbpages-sidebar\u00a0\u00bb][vc_widget_sidebar sidebar_id=\u00a0\u00bbpages_sidebar\u00a0\u00bb el_class=\u00a0\u00bbsidebar\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb9\/12&Prime; el_class=\u00a0\u00bbpages-contenu\u00a0\u00bb][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<div class=\"titre-wrapper\">\n<h1>Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil<\/h1>\n<\/div>\n<p>L\u2019apn\u00e9e obstructive du sommeil survient lorsque les voies a\u00e9riennes deviennent obstru\u00e9es durant le sommeil. Les patients qui en souffrent notent fr\u00e9quemment certains sympt\u00f4mes tels que :<\/p>\n<ul>\n<li>Ronflement<\/li>\n<li>Interruptions dans la respiration<\/li>\n<li>S\u00e9cheresse buccale<\/li>\n<li>Somnolence durant la journ\u00e9e<\/li>\n<li>Gorge irrit\u00e9e<\/li>\n<\/ul>\n<p>La s\u00e9cheresse buccale est souvent associ\u00e9e \u00e0 l\u2019apn\u00e9e du sommeil et peut causer une mauvaise haleine, particuli\u00e8rement le matin. Durant le sommeil, le flot salivaire est diminu\u00e9 et lorsqu\u2019on ajoute la s\u00e9cheresse dans l\u2019\u00e9quation, cela donne un terrain propice au d\u00e9veloppement bact\u00e9rien. Le m\u00e9tabolisme des bact\u00e9ries d\u00e9gage certains produits naus\u00e9abonds qui sont la source de la mauvaise haleine.<\/p>\n<p>Votre dentiste pourrait jouer un r\u00f4le important dans la d\u00e9tection du probl\u00e8me puisqu\u2019on constate aujourd\u2019hui que ce dernier est plus fr\u00e9quemment en contact avec les patients que les m\u00e9decins. Les dentistes sont donc des professionnels de premi\u00e8re ligne qui peuvent vous diriger vers de bons sp\u00e9cialistes lorsque requis. Quand un patient parle de mauvaise haleine avec son dentiste, ce dernier lui posera des questions pour tenter de cibler la cause du probl\u00e8me. Un dentiste bien inform\u00e9 pourrait donc d\u00e9tecter les sympt\u00f4mes de l\u2019apn\u00e9e du sommeil chez un patient et lui recommander un sp\u00e9cialiste afin de confirmer ou non le diagnostic d\u2019apn\u00e9e du sommeil par une polysomnographie.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-4809\" src=\"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/12\/clinique-sommeil-grand-montreal-machoire-dentiste-2-400x180-1-300x135.jpg\" alt=\"Your dentist could detect your sleep apnea\" width=\"300\" height=\"135\" \/>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=\u00a0\u00bb3\/12&Prime; el_class=\u00a0\u00bbpages-sidebar\u00a0\u00bb][vc_widget_sidebar sidebar_id=\u00a0\u00bbpages_sidebar\u00a0\u00bb el_class=\u00a0\u00bbsidebar\u00a0\u00bb][\/vc_column][vc_column width=\u00a0\u00bb9\/12&Prime; el_class=\u00a0\u00bbpages-contenu\u00a0\u00bb][vc_row_inner][vc_column_inner][vc_column_text] Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil L\u2019apn\u00e9e obstructive du sommeil survient lorsque les voies a\u00e9riennes deviennent obstru\u00e9es durant le sommeil. Les patients qui en souffrent notent fr\u00e9quemment certains sympt\u00f4mes tels que : Ronflement Interruptions dans la respiration S\u00e9cheresse buccale Somnolence durant la journ\u00e9e Gorge irrit\u00e9e La &#8230; <a title=\"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil\" class=\"read-more\" href=\"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/\" aria-label=\"En savoir plus sur Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil\">Lire la suite<\/a><\/p>\n","protected":false},"author":20,"featured_media":4508,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[313,319],"class_list":["post-4812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dorma-sleep-clinic","tag-apnee-du-sommeil","tag-ronflement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil - Dormalab<\/title>\n<meta name=\"description\" content=\"Votre dentiste pourrait jouer un r\u00f4le important dans la d\u00e9tection de l&#039;apn\u00e9e puisqu&#039;il est plus fr\u00e9quemment en contact avec les patients que les m\u00e9decins.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil - Dormalab\" \/>\n<meta property=\"og:description\" content=\"Votre dentiste pourrait jouer un r\u00f4le important dans la d\u00e9tection de l&#039;apn\u00e9e puisqu&#039;il est plus fr\u00e9quemment en contact avec les patients que les m\u00e9decins.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/\" \/>\n<meta property=\"og:site_name\" content=\"Dorma Sleep Clinics\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-17T18:10:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-12T15:34:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/12\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"test_user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"test_user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/\"},\"author\":{\"name\":\"test_user\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#\\\/schema\\\/person\\\/5e0d4f2e43a968a72d2e583525a65637\"},\"headline\":\"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil\",\"datePublished\":\"2019-12-17T18:10:01+00:00\",\"dateModified\":\"2021-05-12T15:34:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/\"},\"wordCount\":309,\"publisher\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dormalab.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg\",\"keywords\":[\"Apn\u00e9e du sommeil\",\"Ronflement\"],\"articleSection\":[\"Dorma Sleep Clinic\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/\",\"url\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/\",\"name\":\"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil - Dormalab\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dormalab.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg\",\"datePublished\":\"2019-12-17T18:10:01+00:00\",\"dateModified\":\"2021-05-12T15:34:24+00:00\",\"description\":\"Votre dentiste pourrait jouer un r\u00f4le important dans la d\u00e9tection de l'apn\u00e9e puisqu'il est plus fr\u00e9quemment en contact avec les patients que les m\u00e9decins.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dormalab.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dormalab.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg\",\"width\":1000,\"height\":668,\"caption\":\"Chirurgie palatale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/\",\"name\":\"Dorma Sleep Clinics\",\"description\":\"Sleep Well Live Well\",\"publisher\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#organization\",\"name\":\"Dorma Clinique Du Sommeil\",\"url\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dormalab.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Dorma-Logotype-RGB-Black-scaled-e1578787470924.png\",\"contentUrl\":\"https:\\\/\\\/dormalab.com\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/Dorma-Logotype-RGB-Black-scaled-e1578787470924.png\",\"width\":120,\"height\":25,\"caption\":\"Dorma Clinique Du Sommeil\"},\"image\":{\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dormalab.com\\\/fr\\\/#\\\/schema\\\/person\\\/5e0d4f2e43a968a72d2e583525a65637\",\"name\":\"test_user\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed88f5598c1f9e8efb377d61b5d16ffe41b0feb9aa19343fea085e64210edff5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed88f5598c1f9e8efb377d61b5d16ffe41b0feb9aa19343fea085e64210edff5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ed88f5598c1f9e8efb377d61b5d16ffe41b0feb9aa19343fea085e64210edff5?s=96&d=mm&r=g\",\"caption\":\"test_user\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil - Dormalab","description":"Votre dentiste pourrait jouer un r\u00f4le important dans la d\u00e9tection de l'apn\u00e9e puisqu'il est plus fr\u00e9quemment en contact avec les patients que les m\u00e9decins.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/","og_locale":"fr_FR","og_type":"article","og_title":"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil - Dormalab","og_description":"Votre dentiste pourrait jouer un r\u00f4le important dans la d\u00e9tection de l'apn\u00e9e puisqu'il est plus fr\u00e9quemment en contact avec les patients que les m\u00e9decins.","og_url":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/","og_site_name":"Dorma Sleep Clinics","article_published_time":"2019-12-17T18:10:01+00:00","article_modified_time":"2021-05-12T15:34:24+00:00","og_image":[{"width":1000,"height":668,"url":"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/12\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg","type":"image\/jpeg"}],"author":"test_user","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"test_user","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/#article","isPartOf":{"@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/"},"author":{"name":"test_user","@id":"https:\/\/dormalab.com\/fr\/#\/schema\/person\/5e0d4f2e43a968a72d2e583525a65637"},"headline":"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil","datePublished":"2019-12-17T18:10:01+00:00","dateModified":"2021-05-12T15:34:24+00:00","mainEntityOfPage":{"@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/"},"wordCount":309,"publisher":{"@id":"https:\/\/dormalab.com\/fr\/#organization"},"image":{"@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/#primaryimage"},"thumbnailUrl":"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/12\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg","keywords":["Apn\u00e9e du sommeil","Ronflement"],"articleSection":["Dorma Sleep Clinic"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/","url":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/","name":"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil - Dormalab","isPartOf":{"@id":"https:\/\/dormalab.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/#primaryimage"},"image":{"@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/#primaryimage"},"thumbnailUrl":"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/12\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg","datePublished":"2019-12-17T18:10:01+00:00","dateModified":"2021-05-12T15:34:24+00:00","description":"Votre dentiste pourrait jouer un r\u00f4le important dans la d\u00e9tection de l'apn\u00e9e puisqu'il est plus fr\u00e9quemment en contact avec les patients que les m\u00e9decins.","breadcrumb":{"@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/#primaryimage","url":"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/12\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg","contentUrl":"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/12\/clinique-sommeil-grand-montreal-machoire-dentiste-1.jpg","width":1000,"height":668,"caption":"Chirurgie palatale"},{"@type":"BreadcrumbList","@id":"https:\/\/dormalab.com\/fr\/votre-dentiste-pourrait-detecter-votre-apnee-du-sommeil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dormalab.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Votre dentiste pourrait d\u00e9tecter votre apn\u00e9e du sommeil"}]},{"@type":"WebSite","@id":"https:\/\/dormalab.com\/fr\/#website","url":"https:\/\/dormalab.com\/fr\/","name":"Dorma Sleep Clinics","description":"Sleep Well Live Well","publisher":{"@id":"https:\/\/dormalab.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dormalab.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dormalab.com\/fr\/#organization","name":"Dorma Clinique Du Sommeil","url":"https:\/\/dormalab.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dormalab.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/10\/Dorma-Logotype-RGB-Black-scaled-e1578787470924.png","contentUrl":"https:\/\/dormalab.com\/wp-content\/uploads\/2019\/10\/Dorma-Logotype-RGB-Black-scaled-e1578787470924.png","width":120,"height":25,"caption":"Dorma Clinique Du Sommeil"},"image":{"@id":"https:\/\/dormalab.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dormalab.com\/fr\/#\/schema\/person\/5e0d4f2e43a968a72d2e583525a65637","name":"test_user","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/ed88f5598c1f9e8efb377d61b5d16ffe41b0feb9aa19343fea085e64210edff5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ed88f5598c1f9e8efb377d61b5d16ffe41b0feb9aa19343fea085e64210edff5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed88f5598c1f9e8efb377d61b5d16ffe41b0feb9aa19343fea085e64210edff5?s=96&d=mm&r=g","caption":"test_user"}}]}},"_links":{"self":[{"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/posts\/4812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/comments?post=4812"}],"version-history":[{"count":0,"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/posts\/4812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/media\/4508"}],"wp:attachment":[{"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/media?parent=4812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/categories?post=4812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dormalab.com\/fr\/wp-json\/wp\/v2\/tags?post=4812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}